{"id":4372,"date":"2026-02-05T11:47:51","date_gmt":"2026-02-05T11:47:51","guid":{"rendered":"https:\/\/www.smoothievendingmachine.com\/?p=4372"},"modified":"2026-02-05T11:48:24","modified_gmt":"2026-02-05T11:48:24","slug":"hommy-livemore-lanzamiento-de-smoothie-saludable-en-copec-chile","status":"publish","type":"post","link":"https:\/\/www.smoothievendingmachine.com\/es\/hommy-livemore-lanzamiento-de-smoothie-saludable-en-copec-chile\/","title":{"rendered":"Hommy &amp; Livemore lanzan una venta de batidos saludables en Copec Chile"},"content":{"rendered":"<figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"410\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339.jpg 800w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-300x154.jpg 300w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-768x394.jpg 768w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-18x9.jpg 18w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-585x300.jpg 585w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" title=\"\"><\/figure>\n\n\n<p class=\"wp-block-paragraph\">El mercado chileno est\u00e1 siendo penetrado oficialmente por m\u00e1quinas expendedoras de batidos hommy, que se lanzar\u00e1n por primera vez en la cadena de tiendas de conveniencia m\u00e1s famosa, Coppe. Este lanzamiento estrat\u00e9gico no solo hace que los consumidores chilenos disfruten de una nueva experiencia de bebida saludable, sino que se generar\u00e1 un importante tr\u00e1fico de nuevos clientes a las tiendas Copec. Estos batidos de frutas frescas est\u00e1n atrayendo mucha atenci\u00f3n entre los residentes locales y los turistas por igual.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hommy Smoothie Machine ingresa al chileno en la conocida tienda de conveniencia Copec #VendingMachine\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/7KaobhrX_rY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Perspectivas comerciales: \u00bfPor qu\u00e9 las tiendas de conveniencia prefieren Hommy?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No solo las m\u00e1quinas expendedoras automatizadas, sino que Hommy es un paquete completo de ahorro y diversificaci\u00f3n de ganancias para ofrecer a los minoristas. Las principales fortalezas que hemos combinado son tres pilares de valores fundamentales:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">efectividad operativa final.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo despliegue y uso de espacio: la m\u00e1quina tiene un dise\u00f1o de mesa peque\u00f1a que ocupar\u00e1 solo 0,16 metros. Se puede colocar en una esquina de un mostrador o en un pasillo de alto tr\u00e1fico, y se puede disponer de forma flexible, con la utilizaci\u00f3n m\u00e1s eficiente del espacio de piso (ventas por metro cuadrado).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Automatizaci\u00f3n completa y mano de obra gratuita: la m\u00e1quina estar\u00e1 completamente automatizada y el personal no tendr\u00e1 que supervisar la m\u00e1quina, lo que disminuir\u00e1 significativamente la presi\u00f3n de costos de mano de obra en los procesos diarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Smart Management (IoT): Un sistema IoT unificado brinda la oportunidad de monitorear el inventario y el estado del equipo en tiempo real. Los operadores consiguen reabastecer con precisi\u00f3n, minimizar el desperdicio y eliminar la gesti\u00f3n de ciegas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Servicio al cliente de alta calidad y seguridad.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Servicio r\u00e1pido: la tecnolog\u00eda Scan-to-Pay permite preparar el pedido en uno o dos minutos. Esto funciona mejor en la configuraci\u00f3n de tiendas de conveniencia ocupada donde se minimiza el tiempo que pasa en la cola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Libre de usar: la interfaz f\u00e1cil de usar y sin complicaciones har\u00e1 que todos los clientes, independientemente de su edad, utilicen la m\u00e1quina sin ninguna dificultad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garant\u00eda de higiene: se activar\u00e1 un ciclo de limpieza en cada porci\u00f3n para garantizar que se asegure la seguridad e higiene de todas las bebidas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Maximizaci\u00f3n de ingresos 24\/7<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Canal de ventas de todo el d\u00eda: la m\u00e1quina est\u00e1 libre de las horas de operaci\u00f3n, por lo tanto, responde a la demanda, incluso en los per\u00edodos de desaceleraci\u00f3n para generar ingresos las 24 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valor publicitario: La m\u00e1quina est\u00e1 dise\u00f1ada con lugares publicitarios en el cuerpo y en la pantalla, lo que proporcionar\u00e1 a los operadores una fuente de ingresos extra en t\u00e9rminos de medios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Apoyar la localizaci\u00f3n de soporte de estrategia verde.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hommy ha implementado un futuro plan de sostenibilidad en respuesta a las prohibiciones pl\u00e1sticas m\u00e1s y m\u00e1s estrictas en Chile y en el mercado sudamericano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asociaci\u00f3n local: Livemore (livemore.cl), nuestro socio chileno exclusivo, ofrece servicios locales en el lugar, como suministro de equipos de alto rendimiento y servicios profesionales de instalaci\u00f3n y mantenimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verde: tenemos soluciones de vasos de papel biodegradables certificadas FSC. Esto no solo ayuda a los operadores a cumplir completamente con las leyes y regulaciones locales, sino que tambi\u00e9n se dirige a los consumidores ecol\u00f3gicos, convirti\u00e9ndose as\u00ed en la marca responsable y aumentando la lealtad de los clientes.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4364\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Pronto_Express_Copec_storefront-2955197822.jpg\" alt=\"\" class=\"wp-image-4364\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Pronto_Express_Copec_storefront-2955197822.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Pronto_Express_Copec_storefront-2955197822-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Pronto_Express_Copec_storefront-2955197822-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4370\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_smoothie_vending_machine-0661694128.jpg\" alt=\"\" class=\"wp-image-4370\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_smoothie_vending_machine-0661694128.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_smoothie_vending_machine-0661694128-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_smoothie_vending_machine-0661694128-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4363\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Opening_fruit_yogurt_cup_lid-6310359500.jpg\" alt=\"\" class=\"wp-image-4363\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Opening_fruit_yogurt_cup_lid-6310359500.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Opening_fruit_yogurt_cup_lid-6310359500-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Opening_fruit_yogurt_cup_lid-6310359500-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4369\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_cup_from_vending_machine-4502231517.jpg\" alt=\"\" class=\"wp-image-4369\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_cup_from_vending_machine-4502231517.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_cup_from_vending_machine-4502231517-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fruit_cup_from_vending_machine-4502231517-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4365\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_smoothie_vending_machine-0120848431.jpg\" alt=\"\" class=\"wp-image-4365\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_smoothie_vending_machine-0120848431.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_smoothie_vending_machine-0120848431-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_smoothie_vending_machine-0120848431-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4367\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-7315733537.jpg\" alt=\"\" class=\"wp-image-4367\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-7315733537.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-7315733537-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-7315733537-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4366\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-2529785371.jpg\" alt=\"\" class=\"wp-image-4366\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-2529785371.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-2529785371-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Red_vending_machine_smoothie_retrieval-2529785371-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4362\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Live_More_Smoothie_Cup_Held-1300891645.jpg\" alt=\"\" class=\"wp-image-4362\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Live_More_Smoothie_Cup_Held-1300891645.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Live_More_Smoothie_Cup_Held-1300891645-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Live_More_Smoothie_Cup_Held-1300891645-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"640\" data-id=\"4368\" src=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Two_smoothie_cups_outdoor_table-4600276724.jpg\" alt=\"\" class=\"wp-image-4368\" title=\"\" srcset=\"https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Two_smoothie_cups_outdoor_table-4600276724.jpg 360w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Two_smoothie_cups_outdoor_table-4600276724-169x300.jpg 169w, https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Two_smoothie_cups_outdoor_table-4600276724-7x12.jpg 7w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">sobre hommy<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con 26 a\u00f1os dedicados a su industria, Hommy se ha especializado en la I+D y en la producci\u00f3n de refrigeraci\u00f3n y m\u00e1quinas de procesamiento de alimentos. Tenemos l\u00ednea de productos que consiste en m\u00e1quinas expendedoras de batidos, m\u00e1quinas de yogur congelada y de servicio suave y dispensadores de bebidas fr\u00edas. Tambi\u00e9n ofrecemos servicios profesionales de personalizaci\u00f3n OEM\/ODM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hommy junto con Livemore se dedica a garantizar que la sostenibilidad ambiental se coloque primero y el crecimiento econ\u00f3mico sea impulsado en nombre de nuestros clientes.<\/p>","protected":false},"excerpt":{"rendered":"<p>The Chilean market is officially being penetrated by Hommy smoothie vending machines, which are first going to be launched in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[109],"tags":[],"class_list":["post-4372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"spectra_custom_meta":{"_edit_lock":["1770292147:1"],"rank_math_seo_score":["12"],"rank_math_description":["Hommy and local agent distribute the healthy beverage solutions to the COPEC stores. Have fresh smoothies in sustainable cups that are certified by FSC. Professional installations and support in Chile."],"_thumbnail_id":["4371"],"_edit_last":["1"],"astra_style_timestamp_css":["1783945163"],"_oembed_c438b70ca7567cc9da44b98482325880":["<iframe title=\"Hommy smoothie machine enters the Chilean at the well-known convenience store COPEC #vendingmachine\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/7KaobhrX_rY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_c438b70ca7567cc9da44b98482325880":["1770291961"],"_oembed_634029b69eb8c5e67a65c342cd898ad8":["<iframe title=\"Hommy smoothie machine enters the Chilean at the well-known convenience store COPEC #vendingmachine\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/7KaobhrX_rY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_634029b69eb8c5e67a65c342cd898ad8":["1770291966"],"rank_math_primary_category":["109"],"_wp_old_slug":["%e8%87%aa%e5%8a%a8%e8%8d%89%e7%a8%bf"],"_uag_css_file_name":["uag-css-4372.css"],"_uag_js_file_name":["uag-js-4372.js"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:31761:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\ufeff.uagb-forms__outer-wrap .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-input::placeholder,.uagb-forms__outer-wrap .uagb-forms-input-label,.uagb-forms__outer-wrap .uagb-forms-main-submit-button,.uagb-forms__outer-wrap .uagb-forms-success-message,.uagb-forms__outer-wrap .uagb-forms-failed-message{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.15s;-moz-transition-duration:.15s;-o-transition-duration:.15s;transition-duration:.15s}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]{min-height:0 !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input::-webkit-input-placeholder,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]::-webkit-input-placeholder{overflow:unset}.uagb-forms__outer-wrap .uagb-forms-main-form input:not([type=checkbox]):not([type=radio]):not([type=file]),.uagb-forms__outer-wrap .uagb-forms-main-form textarea,.uagb-forms__outer-wrap .uagb-forms-main-form select{width:100%;box-sizing:border-box}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-checkbox-wrap .uagb-form-checkbox-option input.uagb-inner-input-view{width:33%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-forms-phone-input{width:75% !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%;justify-content:space-between}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .required::after{color:red;content:\" *\"}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-form-hidden-data{display:none}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button.wp-block-button__link{width:auto}.uagb-forms__outer-wrap .uagb-forms-submit-message-hide{display:none}.uagb-forms__outer-wrap .uagb-forms-success-message{padding:20px 20px}.uagb-forms__outer-wrap .uagb-forms-failed-message{padding:20px 20px}.uagb-forms__outer-wrap span.components-spinner{float:none}.uagb-forms__outer-wrap .uagb-forms-input.uagb-form-phone-country{background-color:#fff}.uagb-forms__outer-wrap .uag-col-2-wrap{display:grid;grid-template-columns:1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-3-wrap{display:grid;grid-template-columns:1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-4-wrap{display:grid;grid-template-columns:1fr 1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uagb-switch{position:relative;display:inline-block;width:50px;height:25px}.uagb-forms__outer-wrap .uagb-switch input{width:0;height:0;opacity:0}.uagb-forms__outer-wrap .uagb-slider{position:absolute;top:0;right:0;bottom:0;left:0;background-color:#fff;cursor:pointer;transition:.4s;-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch .uagb-slider::before{position:absolute;width:20px;height:20px;background-color:#000;transition:.4s;content:\"\";-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch input:checked+.uagb-slider::before{background-color:#fff}.uagb-forms__outer-wrap .uagb-slider.round::before{border-radius:50% !important}.uagb-forms-select-box,.uagb-form-phone-country,.uagb-forms-phone-wrap .uagb-forms-phone-input{height:auto;-webkit-appearance:none;appearance:none}.uagb-forms-radio-wrap input[type=radio]:checked+label::before{line-height:1.2;content:\" \"}.uagb-forms-radio-wrap input[type=radio]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\"\"}.uagb-forms-radio-wrap input[type=radio].round+label::before{border-radius:100% !important}select::after,select::before{padding:10px}.uagb-forms-radio-wrap input[type=radio],.uagb-forms-checkbox-wrap input[type=checkbox],.uagb-forms-accept-wrap input[type=checkbox]{opacity:0}.uagb-forms-checkbox-wrap input[type=checkbox]:checked+label::before,.uagb-forms-accept-wrap input[type=checkbox]:checked+label::before{line-height:1.2;content:\"\u2714\"}.uagb-forms-checkbox-wrap input[type=checkbox]+label::before,.uagb-forms-accept-wrap input[type=checkbox]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\" \"}@media only screen and (max-width: 767px){.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%}}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-20 .uagb-forms-main-form{column-gap:20px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-15 .uagb-forms-main-form{column-gap:15px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-10 .uagb-forms-main-form{column-gap:10px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-5 .uagb-forms-main-form{column-gap:5px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-flex-start .uagb-forms-main-form{align-items:flex-start}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-center .uagb-forms-main-form{align-items:center}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form{display:flex;flex-wrap:wrap;margin:0 -5px;position:relative;text-align:left}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-80{width:80%}@media(min-width: 768px)and (max-width: 1024px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}@media(max-width: 767px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}.uagb-block-c0c7044f.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c0c7044f .uagb-forms-main-form textarea{text-align: left;}.uagb-block-c0c7044f .uagb-forms-input{text-align: left;}.uagb-block-c0c7044f .uagb-forms-input-label{display: block;text-align: left;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 15px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input-label{font-weight: 600;font-size: 20px;margin-bottom: 38px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color:  !important;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color:  !important;}.uagb-block-c0c7044f .uagb-slider.round{border-radius: 20px !important;}.uagb-block-c0c7044f .uagb-form-phone-country{background: url(data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: var(--ast-global-color-5);width: 15px;height: 15px;}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: var(--ast-global-color-5);width: 15px;height: 15px;}.uagb-block-c0c7044f .uagb-slider{background-color: var(--ast-global-color-5);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: var(--ast-global-color-2);border-radius: 3px 3px 3px 3px;}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider{background-color: var(--ast-global-color-1);}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: var(--ast-global-color-5);}.uagb-block-c0c7044f .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1pxvar(--ast-global-color-1);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: var(--ast-global-color-5);width: 15px;height: 15px;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-input{padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: var(--ast-global-color-5);background-color: var(--ast-global-color-1);font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: var(--ast-global-color-5);box-shadow: inset 0 0 0 4px var(--ast-global-color-1);font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: var(--ast-global-color-5);background-color: var(--ast-global-color-1);font-size: calc(15px \/ 1.2);}@media only screen and (max-width: 976px) {.uagb-block-c0c7044f.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;margin-bottom: 30px;}.uagb-block-c0c7044f .uagb-slider.round{border-radius: 20px !important;}.uagb-block-c0c7044f .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}@media only screen and (max-width: 767px) {.uagb-block-c0c7044f.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-c0c7044f .uagb-slider.round{border-radius: 20px !important;}.uagb-block-c0c7044f .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: center;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}.uagb-block-c0c7044f.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c0c7044f .uagb-forms-main-form textarea{text-align: left;}.uagb-block-c0c7044f .uagb-forms-input{text-align: left;}.uagb-block-c0c7044f .uagb-forms-input-label{display: block;text-align: left;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 15px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input-label{font-weight: 600;font-size: 20px;margin-bottom: 38px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color:  !important;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color:  !important;}.uagb-block-c0c7044f .uagb-slider.round{border-radius: 20px !important;}.uagb-block-c0c7044f .uagb-form-phone-country{background: url(data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: var(--ast-global-color-5);width: 15px;height: 15px;}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: var(--ast-global-color-5);width: 15px;height: 15px;}.uagb-block-c0c7044f .uagb-slider{background-color: var(--ast-global-color-5);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: var(--ast-global-color-2);border-radius: 3px 3px 3px 3px;}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider{background-color: var(--ast-global-color-1);}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: var(--ast-global-color-5);}.uagb-block-c0c7044f .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1pxvar(--ast-global-color-1);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: var(--ast-global-color-5);width: 15px;height: 15px;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-input{padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: var(--ast-global-color-5);background-color: var(--ast-global-color-1);font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: var(--ast-global-color-5);box-shadow: inset 0 0 0 4px var(--ast-global-color-1);font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: var(--ast-global-color-5);background-color: var(--ast-global-color-1);font-size: calc(15px \/ 1.2);}@media only screen and (max-width: 976px) {.uagb-block-c0c7044f.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;margin-bottom: 30px;}.uagb-block-c0c7044f .uagb-slider.round{border-radius: 20px !important;}.uagb-block-c0c7044f .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}@media only screen and (max-width: 767px) {.uagb-block-c0c7044f.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-c0c7044f .uagb-slider.round{border-radius: 20px !important;}.uagb-block-c0c7044f .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: center;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #BDBDBD;}.uagb-block-c0c7044f .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-c0c7044f .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-c0c7044f .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}\";s:2:\"js\";s:1066:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"c0c7044f\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"afterSubmitToEmail\":\"\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Form Submission\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Please fill up the above captcha.\",\"confirmationUrl\":\"\"}, '.uagb-block-c0c7044f', 4372 );\n});\nwindow.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"c0c7044f\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"afterSubmitToEmail\":\"\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Form Submission\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Please fill up the above captcha.\",\"confirmationUrl\":\"\"}, '.uagb-block-c0c7044f', 4372 );\n});\n });\";s:18:\"current_block_list\";a:19:{i:0;s:24:\"core\/post-featured-image\";i:1;s:14:\"core\/paragraph\";i:2;s:10:\"core\/embed\";i:3;s:12:\"core\/heading\";i:4;s:12:\"core\/gallery\";i:5;s:10:\"core\/image\";i:6;s:11:\"core\/search\";i:7;s:10:\"core\/group\";i:8;s:17:\"core\/latest-posts\";i:9;s:20:\"core\/latest-comments\";i:10;s:13:\"core\/archives\";i:11;s:15:\"core\/categories\";i:12;s:25:\"generateblocks\/query-loop\";i:13;s:23:\"generateblocks\/headline\";i:14;s:19:\"generateblocks\/grid\";i:15;s:24:\"generateblocks\/container\";i:17;s:20:\"generateblocks\/image\";i:18;s:10:\"uagb\/forms\";i:19;s:16:\"uagb\/forms-email\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1783933289\";s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:77:\"https:\/\/fonts.googleapis.com\/css?family=Default&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339.jpg",800,410,false],"thumbnail":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-150x150.jpg",150,150,true],"medium":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-300x154.jpg",300,154,true],"medium_large":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-768x394.jpg",768,394,true],"large":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339.jpg",800,410,false],"1536x1536":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339.jpg",800,410,false],"2048x2048":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339.jpg",800,410,false],"trp-custom-language-flag":["https:\/\/www.smoothievendingmachine.com\/wp-content\/uploads\/Fresh_Smoothies_Vending_Machine_COPEC-3592739339-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.smoothievendingmachine.com\/es\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"The Chilean market is officially being penetrated by Hommy smoothie vending machines, which are first going to be launched in [&hellip;]","_links":{"self":[{"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/posts\/4372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/comments?post=4372"}],"version-history":[{"count":2,"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/posts\/4372\/revisions"}],"predecessor-version":[{"id":4374,"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/posts\/4372\/revisions\/4374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/media\/4371"}],"wp:attachment":[{"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/media?parent=4372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/categories?post=4372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smoothievendingmachine.com\/es\/wp-json\/wp\/v2\/tags?post=4372"}],"curies":[{"name":"pp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}